{"id":7140,"date":"2021-10-08T22:24:52","date_gmt":"2022-05-17T12:18:22","guid":{"rendered":"https:\/\/thee.be\/?post_type=product&#038;p=7140"},"modified":"2024-10-01T12:01:52","modified_gmt":"2024-10-01T10:01:52","slug":"paquet-de-the-les-preferes-de-steffi","status":"publish","type":"product","link":"https:\/\/thee.be\/fr\/shop\/paquets-de-the-fr\/paquet-de-the-les-preferes-de-steffi\/","title":{"rendered":"Paquet de th\u00e9 \u00ab\u00a0Les pr\u00e9f\u00e9r\u00e9s de Steffi\u00a0\u00bb."},"content":{"rendered":"<p>Ce paquet de th\u00e9 contient tous mes th\u00e9s pr\u00e9f\u00e9r\u00e9s de Thee.be. En tant que sommelier du th\u00e9, j&rsquo;aime \u00e9videmment le \u00ab\u00a0vrai\u00a0\u00bb th\u00e9 qui provient du Camellia Sinensis. Mais le soir, je peux aussi vraiment appr\u00e9cier une tisane aux fruits ou aux herbes. Dans ce paquet, je vous ferai \u00e9galement d\u00e9couvrir le rooibos vert, une infusion sp\u00e9ciale d&rsquo;Afrique du Sud qui ne doit pas manquer dans votre armoire \u00e0 th\u00e9.<\/p>\n<p>En outre, j&rsquo;essaie de vous faire voyager dans le monde merveilleux du th\u00e9. Blanc, vert, oolong, noir&#8230; Aussi bien dans sa forme la plus pure que dans les m\u00e9langes. J&rsquo;esp\u00e8re vous surprendre avec ce paquet et vous faire d\u00e9couvrir la grande vari\u00e9t\u00e9 de th\u00e9s disponibles.<\/p>\n<h3>Ce paquet de th\u00e9 est compos\u00e9 de :<\/h3>\n<ul>\n<li>Re-Vitalizer AMBAR, un rooibos vert avec des baies et du moringa. (80 grammes)<\/li>\n<li>Shangri-La AMBAR, un th\u00e9 blanc exclusif du N\u00e9pal (40 g)<\/li>\n<li>Dragon Pearls, des perles de jasmin vertes exclusives pour une tasse de th\u00e9 au jasmin d\u00e9licieusement douce. (50 grammes)<\/li>\n<li>Da Hong Pao, les th\u00e9iers de cet oolong poussent sur un terroir rocheux, d&rsquo;o\u00f9 un go\u00fbt riche en min\u00e9raux. (50 grammes)<\/li>\n<li>Dark Pearl Oolong, un th\u00e9 Oolong exclusif de Ta\u00efwan. (70 grammes)<\/li>\n<li>Honey Black, un th\u00e9 noir exclusif de Ta\u00efwan. (70 grammes)<\/li>\n<li>Jinxuan Oolong, un oolong l\u00e9ger avec des nuances florales et beurr\u00e9es de Tha\u00eflande. (60 grammes)<\/li>\n<li>Honeybush, une tisane sud-africaine connue pour son caract\u00e8re aromatique et doux \u2013 plus sucr\u00e9 que son cousin, le Rooibos. (100 grammes)<\/li>\n<li>Green Wakame, un m\u00e9lange frais de th\u00e9 vert avec de la citronnelle et des algues. (80 grammes)<\/li>\n<li>Long Jing, un th\u00e9 vert de haute qualit\u00e9 de Chine, surnomm\u00e9 \u201cTh\u00e9 de l&rsquo;Empereur\u201d. (70 grammes)<\/li>\n<\/ul>\n<p><em>Veuillez noter que, tr\u00e8s occasionnellement, un th\u00e9 particulier n&rsquo;est pas disponible pendant une p\u00e9riode plus longue. Dans ce cas, nous nous r\u00e9servons le droit de remplacer l&rsquo;un des th\u00e9s de ce forfait par la meilleure alternative possible. Si tel est le cas, nous ferons toujours en sorte de vous envoyer au moins un th\u00e9 de valeur \u00e9gale !<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce paquet de th\u00e9 contient tous mes th\u00e9s pr\u00e9f\u00e9r\u00e9s de Thee.be. En tant que sommelier du th\u00e9, j&rsquo;aime \u00e9videmment le<\/p>\n","protected":false},"featured_media":17774,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[172],"product_tag":[],"class_list":{"0":"post-7140","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-paquets-de-the-fr","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":999999955,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"_links":{"self":[{"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product\/7140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/comments?post=7140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/media\/17774"}],"wp:attachment":[{"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/media?parent=7140"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product_brand?post=7140"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product_cat?post=7140"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product_tag?post=7140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}