{"id":42155,"date":"2026-07-16T14:41:47","date_gmt":"2026-07-16T12:41:47","guid":{"rendered":"https:\/\/thee.be\/?post_type=product&#038;p=42155"},"modified":"2026-08-06T11:34:17","modified_gmt":"2026-08-06T09:34:17","slug":"first-flush-darjeeling-happy-valley-jade","status":"publish","type":"product","link":"https:\/\/thee.be\/fr\/shop\/the-en-vrac\/the-exclusif\/first-flush-darjeeling-happy-valley-jade\/","title":{"rendered":"First Flush Darjeeling Happy Valley JADE"},"content":{"rendered":"<p>Chaque ann\u00e9e, nous choisissons une plantation de th\u00e9 avec laquelle nous collaborons pour notre First Flush Darjeeling. Le \u00ab first flush \u00bb est \u00e0 chaque fois un moment tr\u00e8s attendu par les amateurs de th\u00e9 du monde entier. Le Camellia sinensis, le th\u00e9ier, reste en dormance tout l\u2019hiver, et le First Flush \u2014 ou premi\u00e8re r\u00e9colte \u2014 fournit donc le tout premier th\u00e9 de l\u2019ann\u00e9e. Gr\u00e2ce \u00e0 cette dormance hivernale dans la r\u00e9gion de l\u2019Himalaya, les feuilles de cette r\u00e9colte regorgent d\u2019ar\u00f4mes et de nutriments uniques.<\/p>\n<p>On qualifie parfois le Darjeeling de \u00ab champagne des th\u00e9s \u00bb, et le First Flush peut sans h\u00e9sitation \u00eatre consid\u00e9r\u00e9 comme le Dom P\u00e9rignon des Darjeelings. L\u2019offre de cette r\u00e9colte est limit\u00e9e et la demande mondiale est \u00e9norme. C\u2019est donc avec fiert\u00e9 que nous vous pr\u00e9sentons notre \u00e9dition 2026.<\/p>\n<p>Cette ann\u00e9e, nous avons s\u00e9lectionn\u00e9 la toute premi\u00e8re r\u00e9colte du c\u00e9l\u00e8bre Happy Valley Estate, la deuxi\u00e8me plus ancienne plantation de th\u00e9 de Darjeeling, fond\u00e9e en 1854. Les th\u00e9iers y poussent dans un microclimat unique, \u00e0 2 100 m\u00e8tres d\u2019altitude, et sont \u00e2g\u00e9s d\u2019au moins 80 ans \u2014 certains atteignant m\u00eame 150 ans. En 2007, le domaine Happy Valley Estate est pass\u00e9 enti\u00e8rement \u00e0 la culture biologique.<\/p>\n<p>Ce domaine r\u00e9unit donc tous les \u00e9l\u00e9ments n\u00e9cessaires \u00e0 un th\u00e9 d\u2019exception : le terroir id\u00e9al, la maturit\u00e9 des plants et des g\u00e9n\u00e9rations de savoir-faire. Nous en sommes d\u00e9j\u00e0 de grands admirateurs et particuli\u00e8rement fiers de notre \u00e9dition limit\u00e9e First Flush.<\/p>\n<p><strong>Date de r\u00e9colte :<\/strong> first flush 2026<\/p>\n<p><strong>Ingr\u00e9dients<\/strong><\/p>\n<p>Th\u00e9 noir d\u2019Inde<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Th\u00e9 Darjeeling noir exclusif issu de la premi\u00e8re r\u00e9colte de la saison 2026. Une infusion ambr\u00e9e, riche en saveurs et aux ar\u00f4mes complexes de foin et de fleurs, avec de l\u00e9g\u00e8res notes sucr\u00e9es.<\/p>\n","protected":false},"featured_media":42151,"comment_status":"open","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":""},"product_brand":[306],"product_cat":[132,130,141],"product_tag":[],"class_list":["post-42155","product","type-product","status-publish","has-post-thumbnail","product_brand-jade-fr","product_cat-the-en-vrac","product_cat-the-exclusif","product_cat-the-noir","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":52,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"_links":{"self":[{"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product\/42155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/comments?post=42155"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/media\/42151"}],"wp:attachment":[{"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/media?parent=42155"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product_brand?post=42155"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product_cat?post=42155"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product_tag?post=42155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}