{"id":2736,"date":"2020-12-30T18:56:33","date_gmt":"2020-12-30T17:56:33","guid":{"rendered":"http:\/\/thee.be\/shop\/non%20class\u00e9\/african-affairs\/"},"modified":"2026-07-08T11:45:26","modified_gmt":"2026-07-08T09:45:26","slug":"african-affairs","status":"publish","type":"product","link":"https:\/\/thee.be\/fr\/shop\/sachets-de-the\/sachets-de-the-or-tea\/african-affairs\/","title":{"rendered":"African Affairs Or Tea? (10 sachets)"},"content":{"rendered":"<p>Il y a une histoire derri\u00e8re le nom African Affairs. Une jeune fille s&rsquo;est \u00e9cri\u00e9e : \u00ab\u202fJe suis amoureuse de ce pays et de ses charmants habitants\u202f\u00bb. Les jours pass\u00e8rent, accompagn\u00e9s du lion royal, de la girafe \u00e0 fleurs et du gorille qui tissait pour elle. Les suricates brassaient des rooibos m\u00e9lang\u00e9s \u00e0 des f\u00e8ves de cacao et des raisins. Le parfum \u00e9tait si agr\u00e9able&#8230; qu&rsquo;ils l&rsquo;ont r\u00e9veill\u00e9e ! \u00c9tait-ce juste un r\u00eave ? Une gorg\u00e9e de ce th\u00e9 peut vous ramener dans ce merveilleux endroit.<\/p>\n<p>L&rsquo;ar\u00f4me du caf\u00e9 espresso et l&rsquo;\u00e9quilibre d&rsquo;un petit morceau de chocolat aux truffes lui conf\u00e8rent une saveur douce.<\/p>\n<h3>Composition<\/h3>\n<p>Rooibos (88,5%), raisins (4,8%), ar\u00f4me de truffe, cerneaux de cacao (29%).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a une histoire derri\u00e8re le nom African Affairs. Une jeune fille s&rsquo;est \u00e9cri\u00e9e : \u00ab\u202fJe suis amoureuse de<\/p>\n","protected":false},"featured_media":2302,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[288],"product_cat":[142],"product_tag":[],"class_list":{"0":"post-2736","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-or-tea-fr","7":"product_cat-sachets-de-the-or-tea","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":10,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"_links":{"self":[{"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product\/2736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/comments?post=2736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/media\/2302"}],"wp:attachment":[{"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/media?parent=2736"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product_brand?post=2736"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product_cat?post=2736"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/thee.be\/fr\/wp-json\/wp\/v2\/product_tag?post=2736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}